{"id":824,"count":1,"description":"","link":"https:\/\/eldromedariorecords.com\/web\/tag\/palau-de-la-musica-de-barcelona\/","name":"Palau de la m\u00fasica de Barcelona","slug":"palau-de-la-musica-de-barcelona","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palau de la m\u00fasica de Barcelona Archivos - El Dromedario Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eldromedariorecords.com\/web\/tag\/palau-de-la-musica-de-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palau de la m\u00fasica de Barcelona Archivos - El Dromedario Records\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eldromedariorecords.com\/web\/tag\/palau-de-la-musica-de-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"El Dromedario Records\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\",\"name\":\"El Dromedario Records\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"contentUrl\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"width\":800,\"height\":624,\"caption\":\"El Dromedario Records\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"name\":\"El Dromedario Records\",\"description\":\"Discogr\\u00e1fica El Dromedario Records\",\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/eldromedariorecords.com\/web\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/tag\/palau-de-la-musica-de-barcelona\/#webpage\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/tag\/palau-de-la-musica-de-barcelona\/\",\"name\":\"Palau de la m\\u00fasica de Barcelona Archivos - El Dromedario Records\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/tag\/palau-de-la-musica-de-barcelona\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eldromedariorecords.com\/web\/tag\/palau-de-la-musica-de-barcelona\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/tag\/palau-de-la-musica-de-barcelona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/eldromedariorecords.com\/web\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palau de la m\\u00fasica de Barcelona\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tags\/824"}],"collection":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts?tags=824"},{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tribe_events?tags=824"},{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/portfolio?tags=824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}