{"id":8025,"date":"2020-11-13T11:02:00","date_gmt":"2020-11-13T11:02:00","guid":{"rendered":"https:\/\/eldromedariorecords.com\/web\/?p=8025"},"modified":"2020-11-13T11:02:02","modified_gmt":"2020-11-13T11:02:02","slug":"chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco","status":"publish","type":"post","link":"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/","title":{"rendered":"Chica Sobresalto lanza \u00abFusi\u00f3n del N\u00facleo\u00bb, el explosivo primer single de su nuevo disco"},"content":{"rendered":"\n<h3>Todo el mundo est\u00e1 hablando de su impactante videoclip donde Maialen est\u00e1 encerrada en su habitaci\u00f3n hasta que llega al cl\u00edmax final<\/h3>\n\n\n\n<h3>\u00a1Compra ya\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/baluartesalazero.nirestream.com\/\" target=\"_blank\">aqu\u00ed<\/a>\u00a0tu entrada para el concierto en streaming que dar\u00e1 ma\u00f1ana para celebrar el lanzamiento!<\/h3>\n\n\n\n<p>La espera por fin ha terminado. Chica Sobresalto lanza \u2018Fusi\u00f3n del N\u00facleo\u2019, el esperad\u00edsimo primer single de su nuevo disco. La canci\u00f3n de la que todo el mundo habla ya se puede escuchar\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/links.altafonte.com\/p0v6ymn\" target=\"_blank\">aqu\u00ed<\/a>. Tambi\u00e9n est\u00e1 disponible ya el impactante videoclip donde Maialen est\u00e1 encerrada en su habitaci\u00f3n para vivir esa fusi\u00f3n del n\u00facleo justo antes de sentir que su cabeza y su cuerpo estaban a punto de explotar. \u00a1M\u00edralo\u00a0aqu\u00ed!<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Chica Sobresalto - Fusi\u00f3n del N\u00facleo\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/eU8Qgb6GJF4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p>Pero eso no es todo. Chica Sobresalto ha querido celebrar este lanzamiento con un concierto muy especial para vivir en primera persona la experiencia de la fusi\u00f3n. Ma\u00f1ana s\u00e1bado 14 de noviembre a las 21:00 (hora espa\u00f1ola) se subir\u00e1 a un escenario completamente transformado junto a su pianista Leire Celestino y, entre otros temas, sonar\u00e1 por primera vez \u2018Fusi\u00f3n del N\u00facleo\u2019 en directo. \u00a1A\u00fan puedes comprar tu entrada\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/baluartesalazero.nirestream.com\/chica-sobresalto-concierto?settings=60\" target=\"_blank\">aqu\u00ed<\/a>!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"1000\" height=\"630\" src=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2020\/11\/chica-sobresalto-cartel-streaming-mundial.jpg\" alt=\"\" class=\"wp-image-8018\" srcset=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2020\/11\/chica-sobresalto-cartel-streaming-mundial.jpg 1000w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2020\/11\/chica-sobresalto-cartel-streaming-mundial-300x189.jpg 300w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2020\/11\/chica-sobresalto-cartel-streaming-mundial-768x484.jpg 768w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2020\/11\/chica-sobresalto-cartel-streaming-mundial-705x444.jpg 705w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Todo el mundo est\u00e1 hablando de su impactante videoclip donde Maialen est\u00e1 encerrada en su habitaci\u00f3n hasta que llega al cl\u00edmax final \u00a1Compra ya\u00a0aqu\u00ed\u00a0tu entrada para el concierto en streaming que dar\u00e1 ma\u00f1ana para celebrar el lanzamiento! La espera por fin ha terminado. Chica Sobresalto lanza \u2018Fusi\u00f3n del N\u00facleo\u2019, el esperad\u00edsimo primer single de su [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8024,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[660,45],"tags":[537,1302,1289,1043,1044,120,30],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chica Sobresalto lanza &quot;Fusi\u00f3n del N\u00facleo&quot;, el explosivo primer single de su nuevo disco - El Dromedario Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chica Sobresalto lanza &quot;Fusi\u00f3n del N\u00facleo&quot;, el explosivo primer single de su nuevo disco - El Dromedario Records\" \/>\n<meta property=\"og:description\" content=\"Todo el mundo est\u00e1 hablando de su impactante videoclip donde Maialen est\u00e1 encerrada en su habitaci\u00f3n hasta que llega al cl\u00edmax final \u00a1Compra ya\u00a0aqu\u00ed\u00a0tu entrada para el concierto en streaming que dar\u00e1 ma\u00f1ana para celebrar el lanzamiento! La espera por fin ha terminado. Chica Sobresalto lanza \u2018Fusi\u00f3n del N\u00facleo\u2019, el esperad\u00edsimo primer single de su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/\" \/>\n<meta property=\"og:site_name\" content=\"El Dromedario Records\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-13T11:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-13T11:02:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2020\/11\/fusio\u0301n-del-nucleo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\",\"name\":\"El Dromedario Records\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"contentUrl\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"width\":800,\"height\":624,\"caption\":\"El Dromedario Records\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"name\":\"El Dromedario Records\",\"description\":\"Discogr\\u00e1fica El Dromedario Records\",\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/eldromedariorecords.com\/web\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2020\/11\/fusio\\u0301n-del-nucleo.jpg\",\"contentUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2020\/11\/fusio\\u0301n-del-nucleo.jpg\",\"width\":1000,\"height\":563},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/#webpage\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/\",\"name\":\"Chica Sobresalto lanza \\\"Fusi\\u00f3n del N\\u00facleo\\\", el explosivo primer single de su nuevo disco - El Dromedario Records\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/#primaryimage\"},\"datePublished\":\"2020-11-13T11:02:00+00:00\",\"dateModified\":\"2020-11-13T11:02:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/eldromedariorecords.com\/web\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chica Sobresalto lanza \\u00abFusi\\u00f3n del N\\u00facleo\\u00bb, el explosivo primer single de su nuevo disco\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/#webpage\"},\"author\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\"},\"headline\":\"Chica Sobresalto lanza \\u00abFusi\\u00f3n del N\\u00facleo\\u00bb, el explosivo primer single de su nuevo disco\",\"datePublished\":\"2020-11-13T11:02:00+00:00\",\"dateModified\":\"2020-11-13T11:02:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/#webpage\"},\"wordCount\":221,\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/chica-sobresalto-lanza-fusion-del-nucleo-el-explosivo-primer-single-de-su-nuevo-disco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2020\/11\/fusio\\u0301n-del-nucleo.jpg\",\"keywords\":[\"Chica Sobresalto\",\"Fusi\\u00f3n del n\\u00facleo\",\"Maialen\",\"Maialen Gurbindo\",\"Operaci\\u00f3n Triunfo\",\"single\",\"Videoclip\"],\"articleSection\":[\"Chica Sobresalto\",\"Videoclip\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\",\"name\":\"Iosu\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"caption\":\"Iosu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/8025"}],"collection":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/comments?post=8025"}],"version-history":[{"count":0,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/8025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media\/8024"}],"wp:attachment":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media?parent=8025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/categories?post=8025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tags?post=8025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}