{"id":5853,"date":"2018-10-23T15:38:19","date_gmt":"2018-10-23T15:38:19","guid":{"rendered":"https:\/\/eldromedariorecords.com\/web\/?p=5853"},"modified":"2018-10-23T15:38:19","modified_gmt":"2018-10-23T15:38:19","slug":"inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao","status":"publish","type":"post","link":"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/","title":{"rendered":"Inconscientes, nuevas fechas de presentaci\u00f3n de \u00abNo somos viento\u00bb para Barcelona y Bilbao"},"content":{"rendered":"<p><b>Inconscientes<\/b> recuperar\u00e1n en diciembre dos de los conciertos cancelados en octubre, concretamente los de Barcelona y Bilbao. Las nuevas fechas son el 1 de diciembre para Barcelona (sala Salamandra) y el 28 para Bilbao (sala Azkena).<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5854\" src=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-barcelona.jpg\" alt=\"\" width=\"1000\" height=\"1408\" srcset=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-barcelona.jpg 1000w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-barcelona-213x300.jpg 213w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-barcelona-768x1081.jpg 768w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-barcelona-732x1030.jpg 732w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-barcelona-501x705.jpg 501w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-barcelona-450x634.jpg 450w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Ya est\u00e1n a disposici\u00f3n del p\u00fablico las entradas en la <a href=\"https:\/\/www.ticketmaster.es\/artist\/inconscientes-entradas\/979024?tm_link=tm_featured_attraction_search\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.ticketmaster.es\/artist\/inconscientes-entradas\/979024?tm_link%3Dtm_featured_attraction_search&amp;source=gmail&amp;ust=1540395335474000&amp;usg=AFQjCNF5Ly7E052H-oDUz5df3XOnEUKV2w\">red Ticketamster<\/a>, a 14,00 euros + gastos de distribuci\u00f3n para ambas citas. Pr\u00f3ximamente lo estar\u00e1n en puntos habituales de venta de cada ciudad. En taquilla costar\u00e1n 18,00 euros.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5855\" src=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-bilbao.jpg\" alt=\"\" width=\"1000\" height=\"1408\" srcset=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-bilbao.jpg 1000w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-bilbao-213x300.jpg 213w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-bilbao-768x1081.jpg 768w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-bilbao-732x1030.jpg 732w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-bilbao-501x705.jpg 501w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-bilbao-450x634.jpg 450w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><em><strong>No somos viento<\/strong><\/em>, el disco que est\u00e1n presentando Inconscientes, cuenta con las colaboraciones de<strong> Fito Cabrales, Carlos Tarque<\/strong> y <strong>Kutxi Romero<\/strong>; con este \u00e1lbum, publicado tambi\u00e9n en vinilo, la banda del legendario I\u00f1aki <em>Uoho<\/em> Ant\u00f3n nos sorprende como nunca hizo anteriormente, brind\u00e1ndonos una aut\u00e9ntica joya digna del mejor rock americano hecho en Espa\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inconscientes recuperar\u00e1n en diciembre dos de los conciertos cancelados en octubre, concretamente los de Barcelona y Bilbao. Las nuevas fechas son el 1 de diciembre para Barcelona (sala Salamandra) y el 28 para Bilbao (sala Azkena). Ya est\u00e1n a disposici\u00f3n del p\u00fablico las entradas en la red Ticketamster, a 14,00 euros + gastos de distribuci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5852,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[417],"tags":[193,134,355],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inconscientes, nuevas fechas de presentaci\u00f3n de &quot;No somos viento&quot; para Barcelona y Bilbao - El Dromedario Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inconscientes, nuevas fechas de presentaci\u00f3n de &quot;No somos viento&quot; para Barcelona y Bilbao - El Dromedario Records\" \/>\n<meta property=\"og:description\" content=\"Inconscientes recuperar\u00e1n en diciembre dos de los conciertos cancelados en octubre, concretamente los de Barcelona y Bilbao. Las nuevas fechas son el 1 de diciembre para Barcelona (sala Salamandra) y el 28 para Bilbao (sala Azkena). Ya est\u00e1n a disposici\u00f3n del p\u00fablico las entradas en la red Ticketamster, a 14,00 euros + gastos de distribuci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/\" \/>\n<meta property=\"og:site_name\" content=\"El Dromedario Records\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-23T15:38:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-nuevos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1404\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\",\"name\":\"El Dromedario Records\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"contentUrl\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"width\":800,\"height\":624,\"caption\":\"El Dromedario Records\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"name\":\"El Dromedario Records\",\"description\":\"Discogr\\u00e1fica El Dromedario Records\",\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/eldromedariorecords.com\/web\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-nuevos.jpg\",\"contentUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-nuevos.jpg\",\"width\":2000,\"height\":1404},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/#webpage\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/\",\"name\":\"Inconscientes, nuevas fechas de presentaci\\u00f3n de \\\"No somos viento\\\" para Barcelona y Bilbao - El Dromedario Records\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/#primaryimage\"},\"datePublished\":\"2018-10-23T15:38:19+00:00\",\"dateModified\":\"2018-10-23T15:38:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/eldromedariorecords.com\/web\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inconscientes, nuevas fechas de presentaci\\u00f3n de \\u00abNo somos viento\\u00bb para Barcelona y Bilbao\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/#webpage\"},\"author\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\"},\"headline\":\"Inconscientes, nuevas fechas de presentaci\\u00f3n de \\u00abNo somos viento\\u00bb para Barcelona y Bilbao\",\"datePublished\":\"2018-10-23T15:38:19+00:00\",\"dateModified\":\"2018-10-23T15:38:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/#webpage\"},\"wordCount\":151,\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-nuevas-fechas-de-presentacion-de-no-somos-viento-para-barcelona-y-bilbao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2018\/10\/inconscientes-nuevos.jpg\",\"keywords\":[\"barcelona\",\"Bilbao\",\"Inconscientes\"],\"articleSection\":[\"Inconscientes\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\",\"name\":\"Iosu\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"caption\":\"Iosu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/5853"}],"collection":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/comments?post=5853"}],"version-history":[{"count":0,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/5853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media\/5852"}],"wp:attachment":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media?parent=5853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/categories?post=5853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tags?post=5853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}