{"id":2787,"date":"2016-11-30T11:01:43","date_gmt":"2016-11-30T11:01:43","guid":{"rendered":"https:\/\/eldromedariorecords.com\/web\/?p=2787"},"modified":"2016-11-30T11:01:43","modified_gmt":"2016-11-30T11:01:43","slug":"inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada","status":"publish","type":"post","link":"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/","title":{"rendered":"Inconscientes, \u00abQUIMERAS Y OTRAS REALIDADES\u00bb, a la venta el 9 de diciembre: presentaci\u00f3n del primer single, de la portada y preventa ya activada"},"content":{"rendered":"<p style=\"text-align: left\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-2786\" src=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes.jpg\" alt=\"inconscientes\" width=\"855\" height=\"855\" srcset=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes.jpg 855w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes-80x80.jpg 80w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes-300x300.jpg 300w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes-768x768.jpg 768w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes-600x600.jpg 600w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes-36x36.jpg 36w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes-180x180.jpg 180w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes-705x705.jpg 705w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes-120x120.jpg 120w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes-450x450.jpg 450w\" sizes=\"(max-width: 855px) 100vw, 855px\" \/><\/p>\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">Inconscientes, el grupo formado en 2006 por I\u00f1aki Uoho Ant\u00f3n, est\u00e1n de vuelta: dispuestos a protagonizar el regreso de un gran grupo de rock &amp; roll: he aqu\u00ed, fuera de toda duda, uno de los regresos del a\u00f1o.<\/p>\n<p style=\"text-align: left\">La formaci\u00f3n, al igual que cuando fue creada, se completa con Jon Calvo, a las voces y a las guitarras; Miguel Colino, al bajo; Jos\u00e9 Ignacio Cantera, a la bater\u00eda; y Aiert Erkoreka a los teclados. El pr\u00f3ximo 9 de diciembre ver\u00e1 la luz su segundo trabajo, <b>\u00abQuimeras y otras realidades\u00bb,<\/b> en formato de doble CD. Aprovechamos la ocasi\u00f3n para presentaros &#8216;Otra realidad&#8217;, primer single elegido. <a href=\"https:\/\/www.youtube.com\/watch?v=9LX1F2ChYbU\" target=\"_blank\">Pod\u00e9is escucharlo aqu\u00ed.<\/a><\/p>\n<p style=\"text-align: left\">\u00abQuimeras y otras realidades\u00bb, el esperado segundo disco de Inconscientes, ya se puede reservar con camiseta de regalo <a href=\"http:\/\/inconscientes.net\/\" target=\"_blank\">en la Web del grupo<\/a> por 15,99\u20ac, y <a href=\"https:\/\/eldromedariorecords.com\/web\/tienda\/inconscientes\/\" target=\"_blank\">en la tienda de El Dromedario Records.<\/a> Tambi\u00e9n puede ser reservado en ITunes -en formato digital-, siguiendo el siguiente enlace.<\/p>\n<p style=\"text-align: left\">Adem\u00e1s va a ser posible reservar diferentes PACKS:<br \/>\n&#8211; Disco nuevo + disco anterior (con camiseta); <b>25,99\u20ac<\/b><br \/>\n&#8211; Disco nuevo + entrada (con camiseta); <b>27,99\u20ac<\/b><br \/>\n&#8211; Disco nuevo + disco anterior + entrada (con camiseta); <b>37,99\u20ac<\/b><br \/>\n&#8211; Precio de camiseta; <b>16\u20ac<\/b><br \/>\nEnv\u00edos a domicilio: <b>promoci\u00f3n v\u00e1lida hasta el 9 de diciembre.<\/b><\/p>\n<p style=\"text-align: left\">\u00abQuimeras y otras realidades\u00bb est\u00e1 integrado por 15 canciones, y es un disco en el que hay mucho rock &amp; roll: tintado de blues, rythm &amp; blues, rock sure\u00f1o o hard rock y dibujado con caracter\u00edstica elegancia y preciosismo. Mucho rock &amp; roll escrito con la solera y la sabidur\u00eda brindada por el aprendizaje y la experiencia propia del paso del tiempo. El trabajo, de muy alto voltaje art\u00edstico, denota haber sido creado sin presiones, con los m\u00fasicos disfrutando de su vocaci\u00f3n volc\u00e1ndose en las canciones y recre\u00e1ndose en su hacer tal y como ya hicieron 10 a\u00f1os atr\u00e1s, destapando nuevamente el tarro de las esencias en su nuevo disco.<\/p>\n<p style=\"text-align: left\">Junto a el nuevo disco, se presenta su gira para el 2017:<\/p>\n<p style=\"text-align: left\"><b>ENERO<\/b><br \/>\n27, SANTIAGO, Sala Capitol<br \/>\n28, A CORU\u00d1A, Sala Leclub<br \/>\n<b>FEBRERO<\/b><br \/>\n3, PAMPLONA, Central Caf\u00e9 Teatro<br \/>\n10, TARRAGONA, Sala Zero<br \/>\n11, ZARAGOZA, Sala Las Armas<br \/>\n17, OVIEDO, Sala Sir Laurens<br \/>\n<b>MARZO<\/b><br \/>\n3, MURCIA, Garaje Beat Club<br \/>\n4, VALENCIA, Rosck City<br \/>\n17, BARCELONA, Razzmatazz 2<br \/>\n25, BILBO, Kafe Antzokia<br \/>\n31, MADRID, Sala Pen\u00e9lope<\/p>\n<p style=\"text-align: left\">Inconscientes en <a href=\"https:\/\/www.facebook.com\/inconscientesoficial\/\" target=\"_blank\">Facebook,<\/a> y <a href=\"https:\/\/twitter.com\/Inconscientes_\" target=\"_blank\">Twitter.<\/a><br \/>\n<a href=\"http:\/\/inconscientes.net\/\" target=\"_blank\">inconscientes.net<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inconscientes, el grupo formado en 2006 por I\u00f1aki Uoho Ant\u00f3n, est\u00e1n de vuelta: dispuestos a protagonizar el regreso de un gran grupo de rock &amp; roll: he aqu\u00ed, fuera de toda duda, uno de los regresos del a\u00f1o. La formaci\u00f3n, al igual que cuando fue creada, se completa con Jon Calvo, a las voces y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2786,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[72],"tags":[402,355,79,401],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inconscientes, &quot;QUIMERAS Y OTRAS REALIDADES&quot;, a la venta el 9 de diciembre: presentaci\u00f3n del primer single, de la portada y preventa ya activada - El Dromedario Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inconscientes, &quot;QUIMERAS Y OTRAS REALIDADES&quot;, a la venta el 9 de diciembre: presentaci\u00f3n del primer single, de la portada y preventa ya activada - El Dromedario Records\" \/>\n<meta property=\"og:description\" content=\"Inconscientes, el grupo formado en 2006 por I\u00f1aki Uoho Ant\u00f3n, est\u00e1n de vuelta: dispuestos a protagonizar el regreso de un gran grupo de rock &amp; roll: he aqu\u00ed, fuera de toda duda, uno de los regresos del a\u00f1o. La formaci\u00f3n, al igual que cuando fue creada, se completa con Jon Calvo, a las voces y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/\" \/>\n<meta property=\"og:site_name\" content=\"El Dromedario Records\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-30T11:01:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"855\" \/>\n\t<meta property=\"og:image:height\" content=\"855\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\",\"name\":\"El Dromedario Records\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"contentUrl\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"width\":800,\"height\":624,\"caption\":\"El Dromedario Records\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"name\":\"El Dromedario Records\",\"description\":\"Discogr\\u00e1fica El Dromedario Records\",\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/eldromedariorecords.com\/web\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes.jpg\",\"contentUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes.jpg\",\"width\":855,\"height\":855},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/#webpage\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/\",\"name\":\"Inconscientes, \\\"QUIMERAS Y OTRAS REALIDADES\\\", a la venta el 9 de diciembre: presentaci\\u00f3n del primer single, de la portada y preventa ya activada - El Dromedario Records\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/#primaryimage\"},\"datePublished\":\"2016-11-30T11:01:43+00:00\",\"dateModified\":\"2016-11-30T11:01:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/eldromedariorecords.com\/web\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inconscientes, \\u00abQUIMERAS Y OTRAS REALIDADES\\u00bb, a la venta el 9 de diciembre: presentaci\\u00f3n del primer single, de la portada y preventa ya activada\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/#webpage\"},\"author\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\"},\"headline\":\"Inconscientes, \\u00abQUIMERAS Y OTRAS REALIDADES\\u00bb, a la venta el 9 de diciembre: presentaci\\u00f3n del primer single, de la portada y preventa ya activada\",\"datePublished\":\"2016-11-30T11:01:43+00:00\",\"dateModified\":\"2016-11-30T11:01:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/#webpage\"},\"wordCount\":407,\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/inconscientes-quimeras-otras-realidades-la-venta-9-diciembre-presentacion-del-primer-single-la-portada-preventa-ya-activada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/11\/inconscientes.jpg\",\"keywords\":[\"Gira 2017\",\"Inconscientes\",\"nuevo disco\",\"Quimeras y otras realidades\"],\"articleSection\":[\"Otros\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\",\"name\":\"Iosu\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"caption\":\"Iosu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/2787"}],"collection":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/comments?post=2787"}],"version-history":[{"count":0,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/2787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media\/2786"}],"wp:attachment":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media?parent=2787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/categories?post=2787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tags?post=2787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}