{"id":2702,"date":"2016-10-04T17:03:11","date_gmt":"2016-10-04T17:03:11","guid":{"rendered":"https:\/\/eldromedariorecords.com\/web\/?p=2702"},"modified":"2016-10-04T17:03:11","modified_gmt":"2016-10-04T17:03:11","slug":"la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre","status":"publish","type":"post","link":"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/","title":{"rendered":"La Beriso publica hoy \u00abPECADO CAPITAL\u00bb, disco que ser\u00e1 presentado en el Estadio de River Plate el 17 de diciembre"},"content":{"rendered":"<p style=\"text-align: left\"><img loading=\"lazy\" class=\"size-full wp-image-2703 aligncenter\" src=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital.jpg\" alt=\"laberisopecadocapital\" width=\"665\" height=\"665\" srcset=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital.jpg 665w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital-80x80.jpg 80w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital-300x300.jpg 300w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital-600x600.jpg 600w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital-36x36.jpg 36w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital-180x180.jpg 180w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital-120x120.jpg 120w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital-450x450.jpg 450w\" sizes=\"(max-width: 665px) 100vw, 665px\" \/><\/p>\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">Hoy MARTES 4 de octubre ve la luz \u00abPecado Capital\u00bb, 6\u00b0 disco de estudio de La Beriso. El disco cuenta con la producci\u00f3n de Armando \u00c1vila, ganador de m\u00faltiples premios GRAMMY; pod\u00e9is ver el videoclip del primer single extra\u00eddo, \u00abLegui\u00bb, <a href=\"http:\/\/smarturl.it\/LBlegui\">aqu\u00ed.<\/a><\/p>\n<p style=\"text-align: left\">La Beriso presentar\u00e1 \u00abPecado Capital\u00bb el pr\u00f3ximo 17 de diciembre en el Estadio del Club Atl\u00e9tico River Plate, en un concierto en el que tambi\u00e9n se contar\u00e1 con la presencia de Ciclonautas; como curiosidad apuntaremos que desde 2008 ninguna banda argentina realizaba un show en dicho estadio. La discograf\u00eda de La Beriso se completa con los siguientes \u00e1lbumes: <i>S\u00f3lo canciones<\/i> (2005), <i>Descartando miserias<\/i> (2007), <i>Culpable<\/i> (2009), <i>Atrapando sue\u00f1os<\/i> (2011), <i>Vivo por la gloria<\/i> (CD\/DVD registrado en vivo, 2014) e <i>Historias<\/i>, tambi\u00e9n de 2014.<\/p>\n<p style=\"text-align: left\">Formada en Avellaneda, Buenos Aires, en 1998, La Beriso es la banda de rock argentina que mayor crecimiento ha alcanzado en su pa\u00eds en los \u00faltimos tiempos: Ya en 2015 cerraron el a\u00f1o en el estadio \u00fanico de la Plata ante m\u00e1s de 40.000 personas, para abrir 2016 en ese mismo marco como banda soporte de The Rolling Stones.<\/p>\n<p style=\"text-align: left\">El auge en p\u00fablico y popularidad de La Beriso ha sido a trav\u00e9s del boca a boca, llegando a llenar estadios despu\u00e9s de haber pasado por todo el circuito underground local.<\/p>\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">La Beriso en <a href=\"https:\/\/www.facebook.com\/laberisooficial\">Facebook,<\/a> <a href=\"https:\/\/twitter.com\/laberisorock\">Twitter<\/a> y <a href=\"www.youtube.com\/laberisotv\">Youtube.<\/a><br \/>\n<a href=\"http:\/\/www.laberiso.com.ar\/\">laberiso.com.ar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy MARTES 4 de octubre ve la luz \u00abPecado Capital\u00bb, 6\u00b0 disco de estudio de La Beriso. El disco cuenta con la producci\u00f3n de Armando \u00c1vila, ganador de m\u00faltiples premios GRAMMY; pod\u00e9is ver el videoclip del primer single extra\u00eddo, \u00abLegui\u00bb, aqu\u00ed. La Beriso presentar\u00e1 \u00abPecado Capital\u00bb el pr\u00f3ximo 17 de diciembre en el Estadio del [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[72],"tags":[375,383,376],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Beriso publica hoy &quot;PECADO CAPITAL&quot;, disco que ser\u00e1 presentado en el Estadio de River Plate el 17 de diciembre - El Dromedario Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Beriso publica hoy &quot;PECADO CAPITAL&quot;, disco que ser\u00e1 presentado en el Estadio de River Plate el 17 de diciembre - El Dromedario Records\" \/>\n<meta property=\"og:description\" content=\"Hoy MARTES 4 de octubre ve la luz \u00abPecado Capital\u00bb, 6\u00b0 disco de estudio de La Beriso. El disco cuenta con la producci\u00f3n de Armando \u00c1vila, ganador de m\u00faltiples premios GRAMMY; pod\u00e9is ver el videoclip del primer single extra\u00eddo, \u00abLegui\u00bb, aqu\u00ed. La Beriso presentar\u00e1 \u00abPecado Capital\u00bb el pr\u00f3ximo 17 de diciembre en el Estadio del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/\" \/>\n<meta property=\"og:site_name\" content=\"El Dromedario Records\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-04T17:03:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"665\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\",\"name\":\"El Dromedario Records\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"contentUrl\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"width\":800,\"height\":624,\"caption\":\"El Dromedario Records\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"name\":\"El Dromedario Records\",\"description\":\"Discogr\\u00e1fica El Dromedario Records\",\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/eldromedariorecords.com\/web\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital.jpg\",\"contentUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital.jpg\",\"width\":665,\"height\":665},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/#webpage\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/\",\"name\":\"La Beriso publica hoy \\\"PECADO CAPITAL\\\", disco que ser\\u00e1 presentado en el Estadio de River Plate el 17 de diciembre - El Dromedario Records\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/#primaryimage\"},\"datePublished\":\"2016-10-04T17:03:11+00:00\",\"dateModified\":\"2016-10-04T17:03:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/eldromedariorecords.com\/web\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Beriso publica hoy \\u00abPECADO CAPITAL\\u00bb, disco que ser\\u00e1 presentado en el Estadio de River Plate el 17 de diciembre\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/#webpage\"},\"author\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\"},\"headline\":\"La Beriso publica hoy \\u00abPECADO CAPITAL\\u00bb, disco que ser\\u00e1 presentado en el Estadio de River Plate el 17 de diciembre\",\"datePublished\":\"2016-10-04T17:03:11+00:00\",\"dateModified\":\"2016-10-04T17:03:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/#webpage\"},\"wordCount\":247,\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/la-beriso-publica-hoy-pecado-capital-disco-sera-presentado-estadio-river-plate-17-diciembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/10\/laberisopecadocapital.jpg\",\"keywords\":[\"La Beriso\",\"Pecado capital\",\"River Plate\"],\"articleSection\":[\"Otros\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\",\"name\":\"Iosu\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"caption\":\"Iosu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/2702"}],"collection":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/comments?post=2702"}],"version-history":[{"count":0,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/2702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media\/2703"}],"wp:attachment":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media?parent=2702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/categories?post=2702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tags?post=2702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}