{"id":2192,"date":"2016-02-22T14:30:59","date_gmt":"2016-02-22T14:30:59","guid":{"rendered":"https:\/\/eldromedariorecords.com\/web\/?p=2192"},"modified":"2016-02-22T14:30:59","modified_gmt":"2016-02-22T14:30:59","slug":"ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona","status":"publish","type":"post","link":"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/","title":{"rendered":"Ciclonautas arrasa en Madrid antes de su concierto especial en Pamplona"},"content":{"rendered":"<p style=\"text-align: left\">CICLONAUTAS, el tr\u00edo integrado por Al\u00e9n Ayerdi, Javiertxo Pintor y Mai Medina, llegar\u00e1n el VIERNES 26 plet\u00f3ricos a ZENTRAL, tras reventar en Madrid la sala We Rock; sala que visitaron el viernes 19 con motivo de la presentaci\u00f3n de su 2\u00ba CD, &#8216;Bienvenidos los muertos&#8217;.<\/p>\n<p style=\"text-align: left\">\n<p><img loading=\"lazy\" class=\"size-full wp-image-2193 aligncenter\" src=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/02\/WE-ROCK-LLENA.jpg\" alt=\"We Rock Ciclonautas Madrid 2016\" width=\"720\" height=\"338\" srcset=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/02\/WE-ROCK-LLENA.jpg 720w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/02\/WE-ROCK-LLENA-300x141.jpg 300w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/02\/WE-ROCK-LLENA-600x282.jpg 600w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/02\/WE-ROCK-LLENA-705x331.jpg 705w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/02\/WE-ROCK-LLENA-450x211.jpg 450w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">Fruto del intenso rodaje del grupo durante enero, mes en el que arranc\u00f3 su presente gira &#8216;Vivo o Muerto 2016&#8217;, Ciclonautas se presentaron en Madrid en un estado de forma brutal, ante un p\u00fablico totalmente entregado que abarrot\u00f3 la We Rock.<\/p>\n<p style=\"text-align: left\">El pr\u00f3ximo viernes d\u00eda 26 de febrero la gira llega al coraz\u00f3n de Pamplona, en concreto al Zentral donde Ciclonautas estar\u00e1n acompa\u00f1ados de un mont\u00f3n de amigos y compa\u00f1eros de la actual banda de Loquillo, Marea y Extremoduro.<\/p>\n<p style=\"text-align: left\">La velada ser\u00e1 abierta por IGOR PASKUAL, quien saltar\u00e1 al escenario a partir de las 20.30; guitarrista del grupo del &#8216;Loco&#8217;, el citado aprovechar\u00e1 para presentar su nuevo disco, &#8216;Tierra firme&#8217;. El trabajo es un disco de rock ecl\u00e9ctico y elegante, rotundo y sensible, que utiliza el viejo g\u00e9nero como una tierra firme desde la que huir de la ortodoxia y buscar sus afinidades e influencias. Canciones como \u00abT\u00fa y yo\u00bb, \u00abTierra firme\u00bb, \u00abAlborada\u00bb o \u00abNuevo cine espa\u00f1ol\u00bb presentan a Igor Paskual como el \u00faltimo gran cl\u00e1sico del rock.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CICLONAUTAS, el tr\u00edo integrado por Al\u00e9n Ayerdi, Javiertxo Pintor y Mai Medina, llegar\u00e1n el VIERNES 26 plet\u00f3ricos a ZENTRAL, tras reventar en Madrid la sala We Rock; sala que visitaron el viernes 19 con motivo de la presentaci\u00f3n de su 2\u00ba CD, &#8216;Bienvenidos los muertos&#8217;. Fruto del intenso rodaje del grupo durante enero, mes en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2194,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[35],"tags":[100,27,44,269,195,128,129,268],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ciclonautas arrasa en Madrid antes de su concierto especial en Pamplona - El Dromedario Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciclonautas arrasa en Madrid antes de su concierto especial en Pamplona - El Dromedario Records\" \/>\n<meta property=\"og:description\" content=\"CICLONAUTAS, el tr\u00edo integrado por Al\u00e9n Ayerdi, Javiertxo Pintor y Mai Medina, llegar\u00e1n el VIERNES 26 plet\u00f3ricos a ZENTRAL, tras reventar en Madrid la sala We Rock; sala que visitaron el viernes 19 con motivo de la presentaci\u00f3n de su 2\u00ba CD, &#8216;Bienvenidos los muertos&#8217;. Fruto del intenso rodaje del grupo durante enero, mes en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/\" \/>\n<meta property=\"og:site_name\" content=\"El Dromedario Records\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-22T14:30:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2016\/02\/IMG_6071.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\",\"name\":\"El Dromedario Records\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"contentUrl\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"width\":800,\"height\":624,\"caption\":\"El Dromedario Records\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"name\":\"El Dromedario Records\",\"description\":\"Discogr\\u00e1fica El Dromedario Records\",\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/eldromedariorecords.com\/web\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/02\/IMG_6071.jpg\",\"contentUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/02\/IMG_6071.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/#webpage\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/\",\"name\":\"Ciclonautas arrasa en Madrid antes de su concierto especial en Pamplona - El Dromedario Records\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/#primaryimage\"},\"datePublished\":\"2016-02-22T14:30:59+00:00\",\"dateModified\":\"2016-02-22T14:30:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/eldromedariorecords.com\/web\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciclonautas arrasa en Madrid antes de su concierto especial en Pamplona\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/#webpage\"},\"author\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\"},\"headline\":\"Ciclonautas arrasa en Madrid antes de su concierto especial en Pamplona\",\"datePublished\":\"2016-02-22T14:30:59+00:00\",\"dateModified\":\"2016-02-22T14:30:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/#webpage\"},\"wordCount\":236,\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/ciclonautas-arrasa-en-madrid-antes-de-su-concierto-especial-en-pamplona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2016\/02\/IMG_6071.jpg\",\"keywords\":[\"Al\\u00e9n Ayerdi\",\"Ciclonautas\",\"Concierto\",\"Gira 2016 Vivo o Muerto\",\"Madrid\",\"Mai Medina\",\"Txo Pintor\",\"We Rock\"],\"articleSection\":[\"Ciclonautas\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\",\"name\":\"Iosu\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"caption\":\"Iosu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/2192"}],"collection":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/comments?post=2192"}],"version-history":[{"count":0,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/2192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media\/2194"}],"wp:attachment":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media?parent=2192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/categories?post=2192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tags?post=2192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}