{"id":1986,"date":"2015-12-16T09:56:45","date_gmt":"2015-12-16T09:56:45","guid":{"rendered":"https:\/\/eldromedariorecords.com\/web\/?p=1986"},"modified":"2015-12-16T09:59:21","modified_gmt":"2015-12-16T09:59:21","slug":"1986-2","status":"publish","type":"post","link":"https:\/\/eldromedariorecords.com\/web\/1986-2\/","title":{"rendered":"\u2018La historia de unas canciones que quer\u00edan volar\u2019: VUELO  505, EL LIBRO"},"content":{"rendered":"<p style=\"text-align: left;\">Los riojanos VUELO 505 vieron publicado a finales de septiembre su primer CD,\u00a0\u2018Turbulencias\u2019, \u00e1lbum que fue recibido por la cr\u00edtica de forma totalmente satisfactoria.\u00a0Pues bien, habiendo transcurrido unos meses desde entonces, es un placer para nosotros\u00a0presentaros la pieza que le faltaba al lanzamiento: \u2018La historia de unas canciones que\u00a0quer\u00edan volar\u2019, libro con las letras y las partituras de los temas que representa una\u00a0imprescindible, lujosa y pr\u00e1ctica gu\u00eda de cara a la escucha del disco. Fabricado en un\u00a0formato de gran calidad, ya est\u00e1 a la venta <a href=\"http:\/\/vuelo505.com\/\">en la web del grupo,<\/a> al\u00a0precio de 5\u20ac. Tambi\u00e9n puede ser adquirido junto con el disco al precio total de\u00a015\u20ac.<\/p>\n<p><em><strong>La historia de unas canciones que quer\u00edan volar:<\/strong><\/em><\/p>\n<ul>\n<li>Idea original: <strong>Rub\u00e9n Fern\u00e1ndez Soto<\/strong><\/li>\n<li>Pr\u00f3logo: <strong>Kutxi Romero<\/strong><\/li>\n<li>Dibujos interiores: <strong>Chema Garc\u00eda<\/strong><\/li>\n<li>Dise\u00f1o de portada: <strong>Alexandra Mart\u00ednez<\/strong><\/li>\n<\/ul>\n<p><a href=\"http:\/\/vuelo505.com\/\">vuelo505.com<\/a><br \/>\nVuelo 505 en <a href=\"https:\/\/www.facebook.com\/vuelo505oficial\">Facebook<\/a> y <a href=\"https:\/\/twitter.com\/vuelo505oficial\">Twitter<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los riojanos VUELO 505 vieron publicado a finales de septiembre su primer CD,\u00a0\u2018Turbulencias\u2019, \u00e1lbum que fue recibido por la cr\u00edtica de forma totalmente satisfactoria.\u00a0Pues bien, habiendo transcurrido unos meses desde entonces, es un placer para nosotros\u00a0presentaros la pieza que le faltaba al lanzamiento: \u2018La historia de unas canciones que\u00a0quer\u00edan volar\u2019, libro con las letras y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1678,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[72],"tags":[39,197,70,198,67],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u2018La historia de unas canciones que quer\u00edan volar\u2019: VUELO 505, EL LIBRO - El Dromedario Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eldromedariorecords.com\/web\/1986-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018La historia de unas canciones que quer\u00edan volar\u2019: VUELO 505, EL LIBRO - El Dromedario Records\" \/>\n<meta property=\"og:description\" content=\"Los riojanos VUELO 505 vieron publicado a finales de septiembre su primer CD,\u00a0\u2018Turbulencias\u2019, \u00e1lbum que fue recibido por la cr\u00edtica de forma totalmente satisfactoria.\u00a0Pues bien, habiendo transcurrido unos meses desde entonces, es un placer para nosotros\u00a0presentaros la pieza que le faltaba al lanzamiento: \u2018La historia de unas canciones que\u00a0quer\u00edan volar\u2019, libro con las letras y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eldromedariorecords.com\/web\/1986-2\/\" \/>\n<meta property=\"og:site_name\" content=\"El Dromedario Records\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-16T09:56:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-16T09:59:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2015\/09\/vuelo505.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"579\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\",\"name\":\"El Dromedario Records\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"contentUrl\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"width\":800,\"height\":624,\"caption\":\"El Dromedario Records\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"name\":\"El Dromedario Records\",\"description\":\"Discogr\\u00e1fica El Dromedario Records\",\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/eldromedariorecords.com\/web\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2015\/09\/vuelo505.jpg\",\"contentUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2015\/09\/vuelo505.jpg\",\"width\":1030,\"height\":579,\"caption\":\"Vuelo 505. Turbulencias. Rock en espa\\u00f1ol\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/#webpage\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/\",\"name\":\"\\u2018La historia de unas canciones que quer\\u00edan volar\\u2019: VUELO 505, EL LIBRO - El Dromedario Records\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/#primaryimage\"},\"datePublished\":\"2015-12-16T09:56:45+00:00\",\"dateModified\":\"2015-12-16T09:59:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eldromedariorecords.com\/web\/1986-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/eldromedariorecords.com\/web\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u2018La historia de unas canciones que quer\\u00edan volar\\u2019: VUELO 505, EL LIBRO\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/#webpage\"},\"author\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\"},\"headline\":\"\\u2018La historia de unas canciones que quer\\u00edan volar\\u2019: VUELO 505, EL LIBRO\",\"datePublished\":\"2015-12-16T09:56:45+00:00\",\"dateModified\":\"2015-12-16T09:59:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/#webpage\"},\"wordCount\":166,\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/1986-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2015\/09\/vuelo505.jpg\",\"keywords\":[\"Kutxi Romero\",\"libro\",\"presentaci\\u00f3n\",\"venta\",\"Vuelo 505\"],\"articleSection\":[\"Otros\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/71690da9dcd1ce3d7409664303024b87\",\"name\":\"Iosu\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4225fb5a2e5d3e2effd3ee240c8f8d9d?s=96&d=mm&r=g\",\"caption\":\"Iosu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/1986"}],"collection":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/comments?post=1986"}],"version-history":[{"count":0,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/1986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media\/1678"}],"wp:attachment":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media?parent=1986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/categories?post=1986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tags?post=1986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}