{"id":19624,"date":"2023-05-03T11:06:27","date_gmt":"2023-05-03T09:06:27","guid":{"rendered":"https:\/\/eldromedariorecords.com\/web\/?p=19624"},"modified":"2023-05-03T11:06:28","modified_gmt":"2023-05-03T09:06:28","slug":"presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada","status":"publish","type":"post","link":"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/","title":{"rendered":"Presentamos \u201cBocanada\u201d, nuevo single y videoclip de Bocanada."},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.youtube.com\/watch?v=h6v_mtW6eak\"><img loading=\"lazy\" width=\"800\" height=\"800\" src=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2.jpg\" alt=\"\" class=\"wp-image-19614\" srcset=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2.jpg 800w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2-300x300.jpg 300w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2-80x80.jpg 80w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2-768x768.jpg 768w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2-36x36.jpg 36w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2-180x180.jpg 180w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2-705x705.jpg 705w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>Presentamos \u201cBocanada\u201d, nuevo single y videoclip de Bocanada. El tema ya est\u00e1 en todas las <a href=\"https:\/\/links.altafonte.com\/Bocanada\">plataformas<\/a>.<\/p>\n\n\n\n<p>El videoclip, dirigido por Alex Sanz, nos muestra a una banda sin complejos ni trampa ni cart\u00f3n, haciendo a su libre albedr\u00edo en concierto lo que mejor saben hacer: rock and roll p\u00e9treo con pulsi\u00f3n propia y sin fisuras.<\/p>\n\n\n\n<p>Pod\u00e9is ver el videoclip aqu\u00ed:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.youtube.com\/watch?v=uRinhUXZyZM\"><img loading=\"lazy\" width=\"850\" height=\"467\" src=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/bocanada-bocanada1.jpg\" alt=\"\" class=\"wp-image-19638\" srcset=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/bocanada-bocanada1.jpg 850w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/bocanada-bocanada1-300x165.jpg 300w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/bocanada-bocanada1-768x422.jpg 768w, https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/bocanada-bocanada1-705x387.jpg 705w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a><\/figure>\n\n\n\n<p>En formato quinteto nuevamente tras la vuelta del guitarrista Abel, en puertas de su regreso a la carretera (se materializar\u00e1 el 13 de mayo en Barcelona abriendo para Marea), Bocanada cogen aire con este tema hom\u00f3nimo, erigido sobre las reconocibles constantes vitales del grupo: pura \u2018bocanada\u2019 de rock and roll la canci\u00f3n.<\/p>\n\n\n\n<p>Bocanada, poco m\u00e1s que a\u00f1adir, suma y sigue con el santo y se\u00f1a de la casa por bandera. La fiera, los leones han despertado definitivamente, quedando plasmados sus nuevos rugidos en \u00e9sta, su nueva canci\u00f3n.<\/p>\n\n\n\n<p>Compartimos texto redactado por Mart\u00edn Romero al respecto:<\/p>\n\n\n\n<p><em>\u201cLo primero hola, a todos y todas; desde Bocanada queremos presentaros lo que para nosotros no s\u00f3lo es una nueva canci\u00f3n o un nuevo videoclip, \u201cBocanada\u2019, sino la prueba en estado puro de lo que fuimos, somos y seremos: carne de escenario, capaces de removeros las entra\u00f1as con la seguridad de que el camino que cogimos es el correcto y que podemos hacer palpitar vuestros corazones igual que en estas im\u00e1genes palpitan los nuestros.<\/em><em><\/em><\/p>\n\n\n\n<p><em>Os avisamos de antemano de que esta canci\u00f3n no se quedar\u00e1 sola: hasta pronto.\u201d<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentamos \u201cBocanada\u201d, nuevo single y videoclip de Bocanada. El tema ya est\u00e1 en todas las plataformas. El videoclip, dirigido por Alex Sanz, nos muestra a una banda sin complejos ni trampa ni cart\u00f3n, haciendo a su libre albedr\u00edo en concierto lo que mejor saben hacer: rock and roll p\u00e9treo con pulsi\u00f3n propia y sin fisuras. [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":19614,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[663],"tags":[379],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presentamos \u201cBocanada\u201d, nuevo single y videoclip de Bocanada. - El Dromedario Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentamos \u201cBocanada\u201d, nuevo single y videoclip de Bocanada. - El Dromedario Records\" \/>\n<meta property=\"og:description\" content=\"Presentamos \u201cBocanada\u201d, nuevo single y videoclip de Bocanada. El tema ya est\u00e1 en todas las plataformas. El videoclip, dirigido por Alex Sanz, nos muestra a una banda sin complejos ni trampa ni cart\u00f3n, haciendo a su libre albedr\u00edo en concierto lo que mejor saben hacer: rock and roll p\u00e9treo con pulsi\u00f3n propia y sin fisuras. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/\" \/>\n<meta property=\"og:site_name\" content=\"El Dromedario Records\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-03T09:06:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-03T09:06:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\",\"name\":\"El Dromedario Records\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"contentUrl\":\"https:\/\/eldromedariorecords.melboss.com\/web\/wp-content\/uploads\/2021\/06\/logo-dromedario-negro.png\",\"width\":800,\"height\":624,\"caption\":\"El Dromedario Records\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/\",\"name\":\"El Dromedario Records\",\"description\":\"Discogr\\u00e1fica El Dromedario Records\",\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/eldromedariorecords.com\/web\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2.jpg\",\"contentUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2.jpg\",\"width\":800,\"height\":800},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/#webpage\",\"url\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/\",\"name\":\"Presentamos \\u201cBocanada\\u201d, nuevo single y videoclip de Bocanada. - El Dromedario Records\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/#primaryimage\"},\"datePublished\":\"2023-05-03T09:06:27+00:00\",\"dateModified\":\"2023-05-03T09:06:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/eldromedariorecords.com\/web\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentamos \\u201cBocanada\\u201d, nuevo single y videoclip de Bocanada.\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/#webpage\"},\"author\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/1804798da9a291c9fcd1e97b1adf7446\"},\"headline\":\"Presentamos \\u201cBocanada\\u201d, nuevo single y videoclip de Bocanada.\",\"datePublished\":\"2023-05-03T09:06:27+00:00\",\"dateModified\":\"2023-05-03T09:06:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/#webpage\"},\"wordCount\":267,\"publisher\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/eldromedariorecords.com\/web\/presentamos-bocanada-nuevo-single-y-videoclip-de-bocanada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eldromedariorecords.com\/web\/wp-content\/uploads\/2023\/05\/Bocanada-OK-V2.jpg\",\"keywords\":[\"Bocanada\"],\"articleSection\":[\"Bocanada\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#\/schema\/person\/1804798da9a291c9fcd1e97b1adf7446\",\"name\":\"Gabri\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/eldromedariorecords.com\/web\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/837409c97683bedfc8e1dd6d829bb3c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/837409c97683bedfc8e1dd6d829bb3c1?s=96&d=mm&r=g\",\"caption\":\"Gabri\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/19624"}],"collection":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/comments?post=19624"}],"version-history":[{"count":7,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/19624\/revisions"}],"predecessor-version":[{"id":19640,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/posts\/19624\/revisions\/19640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media\/19614"}],"wp:attachment":[{"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/media?parent=19624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/categories?post=19624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldromedariorecords.com\/web\/wp-json\/wp\/v2\/tags?post=19624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}